{"id":17507,"date":"2022-11-21T16:35:26","date_gmt":"2022-11-21T15:35:26","guid":{"rendered":"https:\/\/thebiopool.com\/?p=17507"},"modified":"2022-11-21T16:44:11","modified_gmt":"2022-11-21T15:44:11","slug":"ibizalivereport","status":"publish","type":"post","link":"https:\/\/thebiopool.com\/it\/ibizalivereport\/","title":{"rendered":"IbizaLiveReport"},"content":{"rendered":"<div id=\"pl-17507\"  class=\"panel-layout\" ><div id=\"pg-17507-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-17507-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-17507-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"so-rounded panel-widget-style panel-widget-style-for-17507-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><img decoding=\"async\" class=\"alignleft wp-image-17510 lazyload\" data-src=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg\" alt=\"theBiopool - against the law\" width=\"650\" height=\"843\" data-srcset=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg 688w, https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz-600x778.jpg 600w, https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz-231x300.jpg 231w\" data-sizes=\"(max-width: 650px) 100vw, 650px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/843;\" \/><img decoding=\"async\" class=\"alignleft wp-image-17509 lazyload\" data-src=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz_2.jpg\" alt=\"theBiopool - against the law\" width=\"650\" height=\"957\" data-srcset=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz_2.jpg 605w, https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz_2-600x884.jpg 600w, https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz_2-204x300.jpg 204w\" data-sizes=\"(max-width: 650px) 100vw, 650px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/957;\" \/><br \/>\n<a href=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22.pdf\">PDF Download - StefanMeier_10-22 - Gegen das Gesetz<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PDF Download &#8211; StefanMeier_10-22 &#8211; Gegen das Gesetz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17507","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IbizaLiveReport - Stefan Meier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebiopool.com\/it\/ibizalivereport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IbizaLiveReport - Stefan Meier\" \/>\n<meta property=\"og:description\" content=\"PDF Download - StefanMeier_10-22 - Gegen das Gesetz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebiopool.com\/it\/ibizalivereport\/\" \/>\n<meta property=\"og:site_name\" content=\"esperti per piscine e stagni naturali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Naturaleza-y-Arte-Stefan-Meier-162702410430553\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T15:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T15:44:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg\" \/>\n<meta name=\"author\" content=\"Stefan Meier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stefan Meier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/ibizalivereport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/ibizalivereport\\\/\"},\"author\":{\"name\":\"Stefan Meier\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/#\\\/schema\\\/person\\\/2066e51311c11b41e9d5c217ab62844f\"},\"headline\":\"IbizaLiveReport\",\"datePublished\":\"2022-11-21T15:35:26+00:00\",\"dateModified\":\"2022-11-21T15:44:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/ibizalivereport\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/ibizalivereport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/StefanMeier_10-22-gegen-das-gesetz.jpg\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/\",\"url\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/\",\"name\":\"IbizaLiveReport - Stefan Meier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/ibizalivereport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/StefanMeier_10-22-gegen-das-gesetz.jpg\",\"datePublished\":\"2022-11-21T15:35:26+00:00\",\"dateModified\":\"2022-11-21T15:44:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/StefanMeier_10-22-gegen-das-gesetz.jpg\",\"contentUrl\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/StefanMeier_10-22-gegen-das-gesetz.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/ibizalivereport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IbizaLiveReport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/\",\"name\":\"TheBiopool\",\"description\":\"progettiamo e creiamo il vostro stagno naturale\",\"publisher\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#organization\",\"name\":\"TheBiopool\",\"url\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/logo-schatten-website-klein.png\",\"contentUrl\":\"https:\\\/\\\/thebiopool.com\\\/wp-content\\\/uploads\\\/logo-schatten-website-klein.png\",\"width\":220,\"height\":64,\"caption\":\"TheBiopool\"},\"image\":{\"@id\":\"https:\\\/\\\/thebiopool.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Naturaleza-y-Arte-Stefan-Meier-162702410430553\\\/\",\"https:\\\/\\\/www.instagram.com\\\/thebiopool\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thebiopool.com\\\/#\\\/schema\\\/person\\\/2066e51311c11b41e9d5c217ab62844f\",\"name\":\"Stefan Meier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g\",\"caption\":\"Stefan Meier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IbizaLiveReport - Stefan Meier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebiopool.com\/it\/ibizalivereport\/","og_locale":"it_IT","og_type":"article","og_title":"IbizaLiveReport - Stefan Meier","og_description":"PDF Download - StefanMeier_10-22 - Gegen das Gesetz","og_url":"https:\/\/thebiopool.com\/it\/ibizalivereport\/","og_site_name":"esperti per piscine e stagni naturali","article_publisher":"https:\/\/www.facebook.com\/Naturaleza-y-Arte-Stefan-Meier-162702410430553\/","article_published_time":"2022-11-21T15:35:26+00:00","article_modified_time":"2022-11-21T15:44:11+00:00","og_image":[{"url":"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg","type":"","width":"","height":""}],"author":"Stefan Meier","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Stefan Meier","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thebiopool.com\/ibizalivereport\/#article","isPartOf":{"@id":"https:\/\/thebiopool.com\/ibizalivereport\/"},"author":{"name":"Stefan Meier","@id":"https:\/\/thebiopool.com\/#\/schema\/person\/2066e51311c11b41e9d5c217ab62844f"},"headline":"IbizaLiveReport","datePublished":"2022-11-21T15:35:26+00:00","dateModified":"2022-11-21T15:44:11+00:00","mainEntityOfPage":{"@id":"https:\/\/thebiopool.com\/ibizalivereport\/"},"wordCount":10,"publisher":{"@id":"https:\/\/thebiopool.com\/#organization"},"image":{"@id":"https:\/\/thebiopool.com\/ibizalivereport\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg","articleSection":["Allgemein"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/thebiopool.com\/it\/ibizalivereport\/","url":"https:\/\/thebiopool.com\/it\/ibizalivereport\/","name":"IbizaLiveReport - Stefan Meier","isPartOf":{"@id":"https:\/\/thebiopool.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebiopool.com\/it\/ibizalivereport\/#primaryimage"},"image":{"@id":"https:\/\/thebiopool.com\/ibizalivereport\/#primaryimage"},"thumbnailUrl":"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg","datePublished":"2022-11-21T15:35:26+00:00","dateModified":"2022-11-21T15:44:11+00:00","breadcrumb":{"@id":"https:\/\/thebiopool.com\/it\/ibizalivereport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/thebiopool.com\/it\/ibizalivereport\/"]]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thebiopool.com\/it\/ibizalivereport\/#primaryimage","url":"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg","contentUrl":"https:\/\/thebiopool.com\/wp-content\/uploads\/StefanMeier_10-22-gegen-das-gesetz.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/thebiopool.com\/it\/ibizalivereport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebiopool.com\/it\/"},{"@type":"ListItem","position":2,"name":"IbizaLiveReport"}]},{"@type":"WebSite","@id":"https:\/\/thebiopool.com\/it\/#website","url":"https:\/\/thebiopool.com\/it\/","name":"TheBiopool","description":"progettiamo e creiamo il vostro stagno naturale","publisher":{"@id":"https:\/\/thebiopool.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebiopool.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/thebiopool.com\/it\/#organization","name":"TheBiopool","url":"https:\/\/thebiopool.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thebiopool.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/thebiopool.com\/wp-content\/uploads\/logo-schatten-website-klein.png","contentUrl":"https:\/\/thebiopool.com\/wp-content\/uploads\/logo-schatten-website-klein.png","width":220,"height":64,"caption":"TheBiopool"},"image":{"@id":"https:\/\/thebiopool.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Naturaleza-y-Arte-Stefan-Meier-162702410430553\/","https:\/\/www.instagram.com\/thebiopool\/"]},{"@type":"Person","@id":"https:\/\/thebiopool.com\/#\/schema\/person\/2066e51311c11b41e9d5c217ab62844f","name":"Stefan Meier","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51b849a4bb46fb0efe8e1b635122fcdc633c2a12fc503f93f431d00136c0d75e?s=96&d=mm&r=g","caption":"Stefan Meier"}}]}},"_links":{"self":[{"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/posts\/17507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/comments?post=17507"}],"version-history":[{"count":0,"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/posts\/17507\/revisions"}],"wp:attachment":[{"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/media?parent=17507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/categories?post=17507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebiopool.com\/it\/wp-json\/wp\/v2\/tags?post=17507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}